{"id":862,"date":"2017-10-03T20:39:58","date_gmt":"2017-10-03T18:39:58","guid":{"rendered":"http:\/\/tsvplattling.de\/?p=862"},"modified":"2017-10-03T20:39:58","modified_gmt":"2017-10-03T18:39:58","slug":"feuchte-wanderung-zu-den-rieslochfaellen","status":"publish","type":"post","link":"https:\/\/www.tsvplattling.de\/index.php\/2017\/10\/03\/feuchte-wanderung-zu-den-rieslochfaellen\/","title":{"rendered":"Feuchte Wanderung zu den Rieslochf\u00e4llen"},"content":{"rendered":"<p>Bereits vor l\u00e4ngerer Zeit plante die Abteilung Lauftreff des TSV Plattling eine gemeinsame Familienwanderung. Es wurde bereits mehrere Wochen vorher der Tag der Deutschen Einheit daf\u00fcr ausgew\u00e4hlt. Das Ziel waren die Rieslochf\u00e4lle bei Bodenmais. F\u00fcr die Organisation des Ausflugs war Katrin Waas zust\u00e4ndig, welche bereits vorab die Wegbeschreibung recherchierte und Platz in einer Gastst\u00e4tte f\u00fcr ein gesellschaftliches Abschlussessen reservierte.<\/p>\n<p>Die Teilnehmer trafen sich um 9 Uhr am Plattlinger Bahnhof um umweltfreundlich \u00fcber Zwiesel nach Bodenmais mit der Waldbahn anzureisen. Der Abteilungsleiter Christian Hamperl konnte zur Wanderung auch den TSV-Vize Markus Schwarz mit seinen Kindern, den Leichtathletik-Vize Thomas Spitlbauer mit seiner Frau als auch den Lauftreff-Vize Fred Wohlleben mit Familie zur Wanderung begr\u00fc\u00dfen. Die Wetterprognosen behielten leider recht und der anf\u00e4ngliche Regen blieb bis zum Nachmittag konstant. Allerdings kennen die wahren L\u00e4ufer sowieso s\u00e4mtliche Wetterkapriolen und waren entsprechend mit Regenjacken und Ponchos und nat\u00fcrlich Wander- statt Laufschuhen bestens ausgestattet. Nach circa eineinhalb Stunden Zugfahrt mit einem Umstieg in Zwiesel erreichten die TSV&#8217;ler den Bahnhof in Bodenmais. \u00dcber die Bahnhofstra\u00dfe, den Ri\u00dflochweg und den gro\u00dfen Wanderparkplatz beim Hotel Waldhaus ging es weiter linkerhand \u00fcber den &#8222;steinigen&#8220; Wanderweg 2 (gr\u00fcn) direkt parallel zum Riesbach und dessen unz\u00e4hligen Wasserf\u00e4lle hinauf zu den eigentlichen Rieslochf\u00e4llen. Durch den starken Regen an diesem und den vorherigen Tagen war der Wasserstand relativ hoch und die Wasserf\u00e4lle sehr imposante Naturph\u00e4nomene. Zeitweilig waren auch die Wege entsprechende Rinnsale mit entsprechend vielen kleinen und gr\u00f6\u00dferen Pf\u00fctzen. Und genau dies war wiederum f\u00fcr die Kinder ein ganz besonderer Reiz. Am n\u00f6rdlichen Wendepunkt des Riesloch Naturschutzgebietes konnte man vor allem auf der Br\u00fccke des Hauptwanderweges die Gischt der Rieslochf\u00e4lle hautnah sp\u00fcren. Nach circa zweieinhalb Stunden erreichten die Wanderer wieder Bodenmais und kehrten beim Adam-Br\u00e4u gem\u00fctlich ein bevor am sp\u00e4ten Nachmittag die Heimreise mit der Waldbahn begann. Die Teilnehmer waren sich einig, dass diese Wanderung ein ganz besonderes Erlebnis war und vor allem bei diesem feuchten Herbstwetter auch sehr lange in Erinnerung bleibt.<\/p>\n<p><a href=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1030.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-866 aligncenter\" src=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1030-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1030-300x225.jpg 300w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1030-768x576.jpg 768w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1030-1024x768.jpg 1024w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1030.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1031-e1507055833707.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-867 aligncenter\" src=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1031-e1507055833707-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1031-e1507055833707-225x300.jpg 225w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1031-e1507055833707-768x1024.jpg 768w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1031-e1507055833707.jpg 1536w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1027.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-864 size-medium aligncenter\" src=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1027-e1507055867834-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1027-e1507055867834-225x300.jpg 225w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1027-e1507055867834-768x1024.jpg 768w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1027-e1507055867834.jpg 1536w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><a href=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1028.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-865 aligncenter\" src=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1028-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1028-300x225.jpg 300w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1028-768x576.jpg 768w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1028-1024x768.jpg 1024w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/IMG_1028.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/20171003_115251_klein.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-863 aligncenter\" src=\"http:\/\/tsvplattling.de\/wp-content\/uploads\/2017\/10\/20171003_115251_klein-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/20171003_115251_klein-225x300.jpg 225w, https:\/\/www.tsvplattling.de\/wp-content\/uploads\/2017\/10\/20171003_115251_klein.jpg 756w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bereits vor l\u00e4ngerer Zeit plante die Abteilung Lauftreff des TSV Plattling eine gemeinsame Familienwanderung. Es wurde bereits mehrere Wochen vorher der Tag der Deutschen Einheit daf\u00fcr ausgew\u00e4hlt. Das Ziel waren die Rieslochf\u00e4lle bei Bodenmais. F\u00fcr die Organisation des Ausflugs war<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-862","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/posts\/862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/comments?post=862"}],"version-history":[{"count":1,"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/posts\/862\/revisions"}],"predecessor-version":[{"id":868,"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/posts\/862\/revisions\/868"}],"wp:attachment":[{"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/media?parent=862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/categories?post=862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tsvplattling.de\/index.php\/wp-json\/wp\/v2\/tags?post=862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}